{"id":68,"date":"2025-07-24T17:01:14","date_gmt":"2025-07-24T15:01:14","guid":{"rendered":"http:\/\/ilonalipp.at\/?page_id=68"},"modified":"2026-03-10T13:59:20","modified_gmt":"2026-03-10T12:59:20","slug":"training","status":"publish","type":"page","link":"https:\/\/ilonalipp.de\/de\/training\/","title":{"rendered":"Training"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"68\" class=\"elementor elementor-68\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37ce08f e-grid e-con-boxed e-con e-parent\" data-id=\"37ce08f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-07268ab e-con-full e-flex e-con e-child\" data-id=\"07268ab\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78fd429 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"78fd429\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00f6chtest du bestimmte F\u00e4higkeiten verbessern?\n<br><br>M\u00f6chtest du effiziente Forschung an deiner Institution f\u00f6rdern?\n<br><br>Bedarfsgerechtes Training kann helfen!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00cb9cf elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"00cb9cf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1457\" height=\"942\" src=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2026\/03\/bilder_compilation_training.jpg\" class=\"attachment-full size-full wp-image-485\" alt=\"\" srcset=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2026\/03\/bilder_compilation_training.jpg 1457w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2026\/03\/bilder_compilation_training-300x194.jpg 300w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2026\/03\/bilder_compilation_training-1024x662.jpg 1024w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2026\/03\/bilder_compilation_training-768x497.jpg 768w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2026\/03\/bilder_compilation_training-18x12.jpg 18w\" sizes=\"(max-width: 1457px) 100vw, 1457px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d76b340 e-flex e-con-boxed e-con e-parent\" data-id=\"d76b340\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c5f145e elementor-widget elementor-widget-spacer\" data-id=\"5c5f145e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e26ad6a elementor-widget elementor-widget-text-editor\" data-id=\"6e26ad6a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ich biete Trainings an, die genau auf deine Bed\u00fcrfnisse zugeschnitten sind. Dabei geht es um F\u00e4higkeiten, die f\u00fcr Wissenschaftler*innen in der akademischen Welt wirklich entscheidend sind. (Hier mehr \u00fcber&nbsp;<a href=\"https:\/\/ilonalipp.de\/de\/about-me\/\"><strong>meine akademische Laufbahn und Lebenslauf<\/strong><\/a>).&nbsp;<\/p>\n<p>M\u00f6gliche Trainingsformate sind&nbsp;<\/p>\n<ul>\n<li>Pr\u00e4senz und Online Trainings<\/li>\n<li>Halbtags-, Ganztags- und mehrt\u00e4tige Workshops f\u00fcr Gruppen<\/li>\n<li>Workshopserien (mehrere k\u00fcrzere Einheiten) f\u00fcr Gruppen<\/li>\n<li>1:1 Trainings<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e5420ea elementor-widget elementor-widget-spacer\" data-id=\"3e5420ea\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a95800f e-flex e-con-boxed e-con e-parent\" data-id=\"a95800f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f71f71e e-con-full e-flex e-con e-child\" data-id=\"f71f71e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e7e087 elementor-widget elementor-widget-heading\" data-id=\"2e7e087\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Themen sind unter anderem:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e854a4 e-grid e-con-boxed e-con e-parent\" data-id=\"7e854a4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb49dec elementor-widget elementor-widget-image\" data-id=\"eb49dec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_56_57-PM.png\" class=\"attachment-large size-large wp-image-225\" alt=\"\" srcset=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_56_57-PM.png 1024w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_56_57-PM-300x300.png 300w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_56_57-PM-150x150.png 150w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_56_57-PM-768x768.png 768w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_56_57-PM-12x12.png 12w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-500b623 elementor-widget elementor-widget-image\" data-id=\"500b623\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_18_23-PM.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-230\" alt=\"\" srcset=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_18_23-PM.png 1024w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_18_23-PM-300x300.png 300w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_18_23-PM-150x150.png 150w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_18_23-PM-768x768.png 768w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_18_23-PM-12x12.png 12w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-399b3c7 elementor-widget elementor-widget-image\" data-id=\"399b3c7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_28_35-PM.png\" class=\"attachment-large size-large wp-image-233\" alt=\"\" srcset=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_28_35-PM.png 1024w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_28_35-PM-300x300.png 300w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_28_35-PM-150x150.png 150w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_28_35-PM-768x768.png 768w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-01_28_35-PM-12x12.png 12w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d2f956 elementor-widget elementor-widget-image\" data-id=\"1d2f956\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_57_11-PM.png\" class=\"attachment-large size-large wp-image-224\" alt=\"\" srcset=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_57_11-PM.png 1024w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_57_11-PM-300x300.png 300w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_57_11-PM-150x150.png 150w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_57_11-PM-768x768.png 768w, http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-22-2025-12_57_11-PM-12x12.png 12w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af99055 elementor-widget elementor-widget-text-editor\" data-id=\"af99055\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4><em>Gute wissenschaftliche Praxis<\/em>\u00a0<\/h4><ul><li>Wissenschaftliche Werte verstehen<\/li><li>Grauzonen in der Wissenschaft<\/li><li>Open Science und andere Werkzeuge um Forschung reproduzierbar, nachhaltig und wirksam zu machen<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05ac2f5 elementor-widget elementor-widget-text-editor\" data-id=\"05ac2f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4><em>Verantwortungsbewusster Umgang mit generativer KI in der Forschung\u00a0<\/em><\/h4><ul><li>Funktionsweisen von KI-basierten Tools<\/li><li>Erkunden diverser Einsatzbereiche in der Forschung<\/li><li>Potenzial und Risiken generativer KI f\u00fcr die Forschung<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b37ad25 elementor-widget elementor-widget-text-editor\" data-id=\"b37ad25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4><em>Praktische F\u00e4higkeiten<\/em><\/h4><ul><li>Effektive und fesselnde wissenschaftliche Pr\u00e4sentationen gestalten<\/li><li>Wissenschaftliches Schreiben<\/li><li>Werkzeuge und Strategien f\u00fcr Datenanalyse<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b319dbe elementor-widget elementor-widget-text-editor\" data-id=\"b319dbe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4><em>Soft skills<\/em><\/h4><ul><li>Konflikte durch effektive Kommunikation vorbeugen und bearbeiten<\/li><li>Pers\u00f6nlichkeitsentwicklung und Karriereplanung<\/li><li>Kreativit\u00e4t in der Wissenschaft<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3164a55 e-flex e-con-boxed e-con e-parent\" data-id=\"3164a55\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0119185 elementor-widget elementor-widget-spacer\" data-id=\"0119185\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3f067d elementor-widget elementor-widget-heading\" data-id=\"e3f067d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Beispiele f\u00fcr Workshops<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a106ecf elementor-widget elementor-widget-n-accordion\" data-id=\"a106ecf\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1680\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1680\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> KI f\u00fcr Datenanalyse: Grundlagen, Praxis, Ethik <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1680\" class=\"elementor-element elementor-element-9123e53 e-flex e-con-boxed e-con e-child\" data-id=\"9123e53\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aebe30d elementor-widget elementor-widget-text-editor\" data-id=\"aebe30d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><!--block-->Dieser Workshop bietet dir eine Einf\u00fchrung in die Nutzung von KI-basierten Systemen zur Datenanalyse. Du bekommst ein grundlegendes Verst\u00e4ndnis daf\u00fcr, wie solche Tools funktionieren, und erforscht, wie man sie praktisch im Forschungsalltag einsetzen kann.<\/p><p>Im Workshop wirst du:<\/p><ul><li><!--block-->die Grundlagen von gro\u00dfen Sprachmodellen und KI-Systemen kennen lernen<\/li><li><!--block-->KI-gest\u00fctzte Tools zur Datenerkundung, Visualisierung und zur Entwicklung von Analyse-Strategien entdecken<\/li><li><!--block-->praktische \u00dcbungen mit tabellarischen Daten machen und dabei KI-Tools einsetzen<\/li><li><!--block-->\u00fcber die M\u00f6glichkeiten und Grenzen dieser Tools im Forschungskontext diskutieren<\/li><li><!--block-->ethische und rechtliche Aspekte sowie bestehende Richtlinien f\u00fcr den verantwortungsvollen Einsatz von KI in der Datenanalyse betrachten<\/li><li><!--block-->dar\u00fcber nachdenken, wie und wann du KI sinnvoll f\u00fcr deine eigenen Daten und Forschungsfragen einsetzen kannst<\/li><\/ul><p><!--block--><\/p><p><!--block-->Der Workshop ist als Halbtages-Workshop konzipiert, kann aber individuell angepasst oder als Teil eines l\u00e4ngeren KI-Workshops angeboten werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1681\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1681\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Br\u00fccken bauen f\u00fcr den Erfolg: Effektive Kommunikation f\u00fcr Wissenschaftler:innen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1681\" class=\"elementor-element elementor-element-a0b9006 e-con-full e-flex e-con e-child\" data-id=\"a0b9006\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1681\" class=\"elementor-element elementor-element-2009943 e-flex e-con-boxed e-con e-child\" data-id=\"2009943\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-277cb47 elementor-widget elementor-widget-text-editor\" data-id=\"277cb47\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Effektive Kommunikation ist der Schl\u00fcssel, um starke Kooperationen aufzubauen, in Meetings von den Beitr\u00e4gen aller zu profitieren und positive Interaktionen in Betreuungsverh\u00e4ltnissen zu f\u00f6rdern. In diesem Workshop werden verschiedene Kommunikationsstrategien vorgestellt und diskutiert. Mit interaktiven \u00dcbungen hast du die M\u00f6glichkeit, unterschiedliche Kommunikationsformen in einem gesch\u00fctzten Rahmen auszuprobieren.<br \/><br \/>Ziel des Workshops ist es, dir zu helfen:<\/p>\n<ul>\n<li>Feedback konstruktiv zu geben<\/li>\n<li>schwierige Gespr\u00e4che souver\u00e4n zu f\u00fchren<\/li>\n<li>Konflikte am Arbeitsplatz zu l\u00f6sen<\/li>\n<li>durch aktives Zuh\u00f6ren bestm\u00f6glich von den Perspektiven deiner Kolleg:innen zu profitieren<\/li>\n<li>deine Wirkung zu steigern, indem du deine eigene Sichtweise erfolgreich durch das Prinzip der gewaltfreien Kommunikation vermittelst<\/li>\n<li>Meetings effektiv zu leiten und zu moderieren<\/li>\n<\/ul>\n<p><br \/>Der Workshop ist f\u00fcr bis zu 12 Teilnehmer:innen konzipiert und wird entweder als 1-t\u00e4gige Version (Grundprinzipien) oder 2-t\u00e4gige Version (mit Arbeit an eigenen Beispielen) angeboten. Abgewandelte Formate beinhalten au\u00dferdem einen halbt\u00e4gigen Teaser-Workshop f\u00fcr bis zu 30 Teilnehmende.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1682\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1682\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kreativit\u00e4t in der Wissenschaft <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1682\" class=\"elementor-element elementor-element-8761039 e-flex e-con-boxed e-con e-child\" data-id=\"8761039\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a137640 elementor-widget elementor-widget-text-editor\" data-id=\"a137640\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wissenschaftliches Arbeiten h\u00e4ngt nicht nur von gr\u00fcndlichen Methoden ab, sondern auch von kreativem Denken \u2013 um neue Theorien zu entwickeln und praktische Probleme zu l\u00f6sen. In diesem Workshop geht es um konkrete Strategien, wie man Kreativit\u00e4tsprozesse aktivieren kann. Du bekommst einen Einblick in die Kreativit\u00e4tsforschung und lernst durch kurze Inputs und praktische \u00dcbungen, wie du flexibler denken, neue Ideen entwickeln und Kreativit\u00e4t gezielt in deine wissenschaftliche Arbeit einbauen kannst.<\/p><p>Ziel des Workshops ist es, dir zu helfen:<\/p><ul><li data-start=\"668\" data-end=\"746\">die Rolle von Kreativit\u00e4t beim wissenschaftlichen Denken und Probleml\u00f6sen besser zu verstehen<\/li><li data-start=\"749\" data-end=\"817\">Methoden kennenzulernen, die flexibles Denken und Ideenfindung unterst\u00fctzen<\/li><li data-start=\"820\" data-end=\"871\">Kreativit\u00e4tstechniken auf echte Forschungsfragen anzuwenden<\/li><li data-start=\"874\" data-end=\"959\">dar\u00fcber zu reflektieren, wie du kreative Prozesse in deinen eigenen Forschungsalltag integrieren kannst<\/li><\/ul><p>Der Workshop ist als Halbtagesveranstaltung konzipiert und eignet sich ideal f\u00fcr Gruppen von 15\u201325 Personen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1683\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1683\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> KI-Tools in der Forschung entdecken: Potenzial, Risiko, Verantwortung <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1683\" class=\"elementor-element elementor-element-0e0e50e e-flex e-con-boxed e-con e-child\" data-id=\"0e0e50e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c980336 elementor-widget elementor-widget-text-editor\" data-id=\"c980336\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Generative KI ver\u00e4ndert gerade rasant, wie Forschung betrieben wird \u2013 von der Literaturrecherche und Datenanalyse bis hin zum Schreiben und Peer Review. In diesem Workshop bekommst du die M\u00f6glichkeit, dich strukturiert mit den praktischen Einsatzm\u00f6glichkeiten von KI-Tools auseinanderzusetzen \u2013 und mit den gr\u00f6\u00dferen Fragen, die sie in Bezug auf wissenschaftliche Integrit\u00e4t und Verantwortung aufwerfen.<\/p><p>Im Workshop wirst du:<\/p><ul><li>praktische Forschungsaufgaben mit generativen KI-Tools bearbeiten und die Qualit\u00e4t, Zuverl\u00e4ssigkeit und Transparenz der Ergebnisse einsch\u00e4tzen<\/li><li>dar\u00fcber diskutieren, ab wann und in welchem Kontext der KI-Einsatz problematisch wird \u2013 im Hinblick auf gute wissenschaftliche Praxis und Prinzipien der Open Science<\/li><li>dar\u00fcber nachdenken, was es bedeutet, geistige Arbeit an mathematische Modelle auszulagern und Daten mit kommerziellen Plattformen zu teilen<\/li><li>analysieren, wie bestehende ethische und institutionelle Richtlinien auf reale Forschungssituationen mit generativer KI angewendet werden k\u00f6nnen<\/li><li>eigene Kriterien entwickeln, wie du KI verantwortungsvoll in deinen wissenschaftlichen Workflow integrieren kannst<\/li><\/ul><p>Der Workshop kann in Umfang und Schwerpunkt angepasst werden \u2013 von kurzen Einf\u00fchrungssessions bis hin zu ganzt\u00e4gigen Formaten.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1684\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1684\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Gute wissenschaftliche Praxis <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1684\" class=\"elementor-element elementor-element-c169fca e-flex e-con-boxed e-con e-child\" data-id=\"c169fca\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea51fba elementor-widget elementor-widget-text-editor\" data-id=\"ea51fba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Gute wissenschaftliche Praxis ist das Fundament f\u00fcr vertrauensw\u00fcrdige Forschung und wissenschaftlichen Fortschritt. In diesem Workshop schauen wir uns die zentralen Prinzipien sowohl aus systemischer als auch aus praktischer Perspektive an. Durch kurze Inputs, Reflexions\u00fcbungen und Fallbeispiele bekommst du die M\u00f6glichkeit, abstrakte Regeln mit deinem Forschungsalltag zu verkn\u00fcpfen.<\/p><p data-start=\"518\" data-end=\"559\">Ziel des Workshops ist es, dir zu helfen:<\/p><ul><li data-start=\"563\" data-end=\"703\">zentrale Begriffe wie gute wissenschaftliche Praxis, wissenschaftliches Fehlverhalten, fragw\u00fcrdige Forschungspraktiken und verantwortungsvolle Forschung besser zu verstehen<\/li><li data-start=\"706\" data-end=\"788\">Rollen und Verantwortlichkeiten rund um Forschungsethik und Integrit\u00e4t zu kl\u00e4ren<\/li><li data-start=\"791\" data-end=\"906\">dich mit relevanten Richtlinien und Verhaltenskodizes vertraut zu machen (z.\u202fB. DFG-Leitlinien, institutsinterne Regelungen)<\/li><li data-start=\"909\" data-end=\"1012\">zu reflektieren, wie wissenschaftliche Strukturen und Forschungskultur die Umsetzung guter Praxis erschweren k\u00f6nnen<\/li><li data-start=\"1015\" data-end=\"1090\">reale Grauzonen und individuelle Dilemmata aus dem Forschungsalltag zu analysieren<\/li><li data-start=\"1093\" data-end=\"1170\">zu \u00fcberlegen, wie gute wissenschaftliche Praxis im Umgang mit generativer KI angewendet werden kann<\/li><\/ul><p>Der Workshop kann in Umfang und Tiefe flexibel angepasst werden \u2013 von kurzen Einf\u00fchrungen bis hin zu ausf\u00fchrlicheren Formaten mit viel Praxisbezug.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1685\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1685\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Wissenschaftliche Pr\u00e4sentationen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1685\" class=\"elementor-element elementor-element-242b5a4 e-con-full e-flex e-con e-child\" data-id=\"242b5a4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5906b6 elementor-widget elementor-widget-text-editor\" data-id=\"f5906b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wer die Kunst der wissenschaftlichen Pr\u00e4sentation beherrscht, kann komplexe Ideen verst\u00e4ndlich vermitteln und nachhaltig Eindruck hinterlassen.<\/p><p>In diesem Workshop lernst du verschiedene Strategien kennen, um \u00fcberzeugende Pr\u00e4sentationen vorzubereiten und zu halten. Anhand konkreter Beispiele analysieren wir, was gute wissenschaftliche Vortr\u00e4ge ausmacht. In praktischen \u00dcbungen wendest du das Gelernte direkt auf dein eigenes Thema an und bekommst konstruktives Feedback \u2013 in einem sicheren und unterst\u00fctzenden Rahmen.<\/p><p>Der Workshop hilft dir dabei:<\/p><ul><li>zentrale Botschaften und Kernaussagen aus komplexen Inhalten herauszuarbeiten<\/li><li>Inhalte sinnvoll zu strukturieren und mit einer klaren Erz\u00e4hlweise verst\u00e4ndlicher und einpr\u00e4gsamer zu machen<\/li><li>visuelle Darstellungen gezielt einzusetzen und Folien so zu gestalten, dass sie klar und \u00fcbersichtlich sind<\/li><li>Strategien zu entwickeln, wie du mit deinem Publikum in Kontakt kommst und es aktiv einbindest<\/li><li>mit einer positiven Haltung und mehr Selbstvertrauen an wissenschaftliche Vortr\u00e4ge heranzugehen<\/li><\/ul><p>Am Ende des Workshops gehst du nicht nur mit konkreten Ergebnissen nach Hause, sondern auch mit einem praktischen Werkzeugkasten an Strategien, die du bei k\u00fcnftigen Pr\u00e4sentationen direkt einsetzen kannst.<\/p><p>Der Workshop kann als eint\u00e4giges oder erweitertes zweit\u00e4giges Format angeboten werden und eignet sich ideal f\u00fcr Gruppen mit maximal 20 Teilnehmenden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1686\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1686\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Machine Learning mit Python meistern <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1686\" class=\"elementor-element elementor-element-7d8a32c e-flex e-con-boxed e-con e-child\" data-id=\"7d8a32c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f2559b elementor-widget elementor-widget-text-editor\" data-id=\"3f2559b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ich biete Workshops zu Python und Machine Learning an in Zusammenarbeit mit\u00a0<a href=\"https:\/\/alexbritz.de\/data-analysis-with-python\/\" target=\"_blank\" rel=\"noopener\">Dr. Alex Britz<\/a>.\u00a0<\/p><p>In diesem 3-t\u00e4gigen Workshop bekommst du eine solide Grundlage in den wichtigsten Konzepten des maschinellen Lernens, vertiefst deine Python-Kenntnisse und arbeitest an praktischen Anwendungen.<\/p><p>Durch eine Mischung aus theoretischem Input und praktischen \u00dcbungen wirst du:<\/p><ul><li>die grundlegenden Prinzipien von Machine Learning zu verstehen und wie du Daten sinnvoll vorbereitest<\/li><li>deine Python-Skills gezielt zu erweitern \u2013 mit Fokus auf fortgeschrittene Konzepte f\u00fcr ML-Projekte.<\/li><li>virtuelle Umgebungen zu erstellen und Versionskontrolle mit Git effektiv zu nutzen.<\/li><li>\u00fcberwachte Lernverfahren mit der Scikit-Learn-Bibliothek anzuwenden.<\/li><li>erste Schritte mit neuronalen Netzen und Deep-Learning-Frameworks wie PyTorch zu machen.<\/li><\/ul><p>Am Ende des Workshops hast du nicht nur ein solides konzeptionelles Verst\u00e4ndnis, sondern auch konkrete praktische Skills, die du direkt in deinen eigenen Machine-Learning-Projekten einsetzen kannst.<\/p><p>Der Workshop ist ideal f\u00fcr kleine Gruppen mit maximal 12 Teilnehmenden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1687\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1687\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Einf\u00fchrung in das wissenschaftliche Programmieren mit Python <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1687\" class=\"elementor-element elementor-element-924c47f e-flex e-con-boxed e-con e-child\" data-id=\"924c47f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3979078 elementor-widget elementor-widget-text-editor\" data-id=\"3979078\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ich biete Workshops zu Python und Machine Learning an in Zusammenarbeit mit\u00a0<a href=\"https:\/\/alexbritz.de\/data-analysis-with-python\/\" target=\"_blank\" rel=\"noopener\">Dr. Alex Britz<\/a>.\u00a0<\/p><p>Dieser 2-t\u00e4gige Workshop ist darauf ausgelegt, dir eine solide Grundlage im wissenschaftlichen Programmieren mit Python zu vermitteln.<\/p><p>Durch eine Mischung aus theoretischem Input und praktischen \u00dcbungen wirst du:<\/p><ul><li>einen \u00dcberblick \u00fcber die Vielseitigkeit von Python anhand von Anwendungsbeispielen bekommen.<\/li><li>lernen, wie man Python installiert und loslegt: Jupyter Notebooks, Spyder, Anaconda, Kommandozeile<\/li><li>in die Python-Syntax eintauchen: Datentypen und Variablen, Bedingungen, Schleifen und Funktionen.<\/li><li>das Lesen und Schreiben von Dateien umsetzen.<\/li><li>erste Schritte in der Datenverarbeitung mit Numpy und Datenvisualisierung mit Matplotlib durchlaufen.<\/li><li>das Gelernte direkt an deinen eigenen Daten und Fragestellungen ausprobieren.<\/li><\/ul><p>Der Workshop ist ideal f\u00fcr Gruppen mit maximal 12 Teilnehmenden geeignet. Es sind keine Vorkenntnisse im Programmieren n\u00f6tig.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1688\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"9\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1688\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Verantwortungsvolle Forschung &amp; Open Science: Entwicklungen und Auswirkungen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1688\" class=\"elementor-element elementor-element-5f746b0 e-flex e-con-boxed e-con e-child\" data-id=\"5f746b0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e56b72 elementor-widget elementor-widget-text-editor\" data-id=\"0e56b72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Bewegungen wie Responsible Research und Open Science gewinnen im globalen Wissenschaftssystem immer mehr an Bedeutung.\nIn diesem interaktiven Workshop bekommst du einen umfassenden Einblick in zentrale Konzepte und hast die M\u00f6glichkeit, dar\u00fcber nachzudenken, wie diese Entwicklungen deine wissenschaftliche Praxis und deine Karriere beeinflussen.<\/p><p>Im Workshop wirst du:<\/p><ul><li>die Konzepte verantwortungsbewusste Forschung, Open Science, gute wissenschaftliche Praxis und Forschungsbewertung kennenlernen<\/li><li>in \u00dcbungen und Diskussionen reflektieren, wie sich diese Ans\u00e4tze konkret auf deine eigene Forschung (bzw. dein Fachgebiet) anwenden lassen<\/li><li>deine Rolle als Wissenschaftler:in im Verh\u00e4ltnis zu Arbeitgeber, Community und Gesellschaft reflektieren<\/li><li>erkunden, welche Faktoren verantwortungsvolle Forschung erleichtern oder erschweren<\/li><li>diskutieren, welche Auswirkungen verantwortungsvolle Forschung auf Karrierewege hat \u2013 und welche Strategien dir helfen k\u00f6nnen, dich gut darin zu positionieren<\/li><\/ul><p>Der Workshop kann je nach Interesse angepasst werden \u2013 z.\u202fB. mit Fokus auf europ\u00e4ische Entwicklungen, deutsche Regelwerke oder konkrete Open-Science-Praktiken.\n\nM\u00f6gliche Formate reichen von kurzen Einf\u00fchrungs-Sessions bis hin zu ganzt\u00e4gigen Workshops.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1689\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"10\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1689\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Confidence Boost: Mit Theatertechniken zu mehr Pr\u00e4senz und Wirkung beim Pr\u00e4sentieren <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1689\" class=\"elementor-element elementor-element-bd441e7 e-con-full e-flex e-con e-child\" data-id=\"bd441e7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7111fd elementor-widget elementor-widget-text-editor\" data-id=\"c7111fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Gute Pr\u00e4sentationsskills und ein sicheres Auftreten sind entscheidend, um in unterschiedlichsten Situationen \u2013 ob bei Konferenzen, Bewerbungsgespr\u00e4chen, Meetings oder Diskussionen \u2013 nachhaltig zu \u00fcberzeugen.\nIn diesem lebendigen und praxisorientierten Workshop arbeiten wir mit Methoden aus dem Theater, um deine Kommunikationsf\u00e4higkeiten zu st\u00e4rken und dein Selbstvertrauen sp\u00fcrbar zu steigern.\n\nIn einem sicheren, unterst\u00fctzenden und zugleich spielerischen Rahmen kannst du mit K\u00f6rpersprache, Stimme und Ausdruck experimentieren \u2013 und bekommst ehrliches, konstruktives Feedback.<br \/><br \/>Tag 1 steht im Zeichen der Grundlagen: Du lernst zentrale Prinzipien kennen und wirst behutsam an theatrale \u00dcbungen herangef\u00fchrt, um dich mit den Techniken vertraut zu machen.\nTag 2 ist praxisorientiert: Wir arbeiten an konkreten Beispielen aus deinem Alltag, damit du die \u00dcbungen direkt auf deine eigenen Kommunikations- und Pr\u00e4sentationssituationen \u00fcbertragen kannst. Ziel des Workshops ist nicht, dir \u201eSchauspiel\u201c beizubringen \u2013 sondern dir zu helfen, dein eigenes Kommunikationsverhalten besser kennenzulernen und neue Ausdrucksm\u00f6glichkeiten auszuprobieren.\nDurch Theatermethoden lernst du, deine Wirkung bewusster zu steuern und dich mit mehr Klarheit, Pr\u00e4senz und Leichtigkeit zu zeigen.\u00a0<br \/><br \/>Der Workshop eignet sich ideal f\u00fcr kleine Gruppen mit maximal 10 Teilnehmenden und entfaltet seine volle Wirkung als zweit\u00e4giges Format.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84fb6a9 e-flex e-con-boxed e-con e-parent\" data-id=\"84fb6a9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-102874da e-flex e-con-boxed e-con e-parent\" data-id=\"102874da\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d88a31b elementor-widget elementor-widget-spacer\" data-id=\"3d88a31b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d880426 elementor-widget elementor-widget-heading\" data-id=\"7d880426\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum Training?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9484df elementor-widget elementor-widget-text-editor\" data-id=\"f9484df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Exzellente Wissenschaft braucht mehr als nur Fachwissen und technische Skills. Besonders Selbstmanagement und kommunikative F\u00e4higkeiten sind entscheidend, um Forschung effizient und erfolgreich durchzuf\u00fchren. Gutes wissenschaftliches Schreiben und \u00fcberzeugende Pr\u00e4sentationen tragen wesentlich dazu bei, dass deine Forschung Wirkung zeigt.\n\nWenn du in der Wissenschaft erfolgreich sein willst, wirst du immer wieder in Situationen kommen, in denen du deine Arbeit klar und selbstbewusst pr\u00e4sentieren, verhandeln, mit inneren Konflikten umgehen oder schwierige Gespr\u00e4che f\u00fchren musst.\n\nGezieltes Training hilft dir dabei, genau diese Herausforderungen souver\u00e4n zu meistern \u2013 und gibt dir Werkzeuge an die Hand, mit denen du alle Seiten des akademischen Lebens gut navigieren kannst.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2a9939 elementor-widget elementor-widget-spacer\" data-id=\"b2a9939\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-542eeea5 e-flex e-con-boxed e-con e-parent\" data-id=\"542eeea5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68c6f4db elementor-widget elementor-widget-spacer\" data-id=\"68c6f4db\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f52a99a elementor-widget elementor-widget-heading\" data-id=\"4f52a99a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Was dich erwartet<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0708b6 elementor-widget elementor-widget-text-editor\" data-id=\"c0708b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Meine Trainings basieren auf den F\u00e4higkeiten, die ich mir w\u00e4hrend meiner wissenschaftlichen Laufbahn, meiner Lehrerfahrung und meiner Expertise im Bereich Kommunikation angeeignet habe. In meinen Workshops bekommen die Teilnehmenden konkrete Werkzeuge und Strategien an die Hand und haben gleichzeitig die M\u00f6glichkeit, diese in einem gesch\u00fctzten Rahmen auszuprobieren und auf ihre eigenen Situationen zu \u00fcbertragen.\n\nDurch meine Ausbildung als Mediatorin und meine Leidenschaft f\u00fcrs Improvisationstheater kann ich flexibel und individuell auf die Bed\u00fcrfnisse und Beitr\u00e4ge der Teilnehmenden eingehen. Als Wissenschaftlerin lege ich au\u00dferdem gro\u00dfen Wert darauf, theoretische Inhalte fundiert, kritisch und evidenzbasiert zu vermitteln.\n\nIch gestalte meine Trainings so forschungsnah wie m\u00f6glich. Das hei\u00dft: Ich halte mich \u00fcber aktuelle Erkenntnisse aus der Lern- und Trainingsforschung auf dem Laufenden und tausche mich regelm\u00e4\u00dfig mit meinem Trainer:innen-Netzwerk aus, damit meine Workshops nicht nur praxisnah, sondern auch didaktisch fundiert sind.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20180165 elementor-widget elementor-widget-spacer\" data-id=\"20180165\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fcfe47 e-flex e-con-boxed e-con e-parent\" data-id=\"1fcfe47\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-912be28 elementor-widget elementor-widget-spacer\" data-id=\"912be28\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5e32a elementor-widget elementor-widget-heading\" data-id=\"dc5e32a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wann ist Training nicht das richtige Werkzeug<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f1d988 elementor-widget elementor-widget-text-editor\" data-id=\"0f1d988\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ziel meiner Trainings ist es, dir F\u00e4higkeiten zu vermitteln, die du direkt auf deine individuelle Situation anwenden kannst. Wenn du jedoch konkrete Unterst\u00fctzung bei pers\u00f6nlichen Herausforderungen oder Konflikten suchst, ist ein Training nicht das passende Format, sondern besser <a href=\"https:\/\/ilonalipp.de\/de\/my-offer\/coaching\/\"><strong>Coaching<\/strong><\/a>\u00a0oder\u00a0<a href=\"https:\/\/ilonalipp.de\/de\/my-offer\/mediation\/\"><strong>Mediation<\/strong><\/a>.<br \/><br \/>Meine Trainings sind sehr interaktiv und leben von der aktiven Beteiligung und Reflexion der Teilnehmenden. Wenn du also jemanden suchst, der ausschlie\u00dflich theoretischen Input liefert oder vortr\u00e4gt, sind meine Workshops vermutlich nicht das Richtige f\u00fcr dich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c6ecd5 elementor-widget elementor-widget-spacer\" data-id=\"7c6ecd5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cc86be e-flex e-con-boxed e-con e-parent\" data-id=\"5cc86be\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b5f0c4 elementor-widget elementor-widget-spacer\" data-id=\"7b5f0c4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c5eaf5 elementor-widget elementor-widget-heading\" data-id=\"8c5eaf5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">N\u00e4chste Schritte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9037d elementor-widget elementor-widget-text-editor\" data-id=\"1f9037d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><a href=\"https:\/\/ilonalipp.de\/de\/contact\/\" target=\"_self\"><strong>Melde dich bei mir <\/strong><\/a>und dann besprechen wir gemeinsam Rahmen, Format und Kosten deines individuellen Trainings. Die Trainings k\u00f6nnen sowohl virtuell als auch vor Ort stattfinden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd823a5 elementor-widget elementor-widget-spacer\" data-id=\"bd823a5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03beb54 e-flex e-con-boxed e-con e-parent\" data-id=\"03beb54\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c6d5d8 elementor-widget elementor-widget-premium-carousel-widget\" data-id=\"2c6d5d8\" data-element_type=\"widget\" data-widget_type=\"premium-carousel-widget.default\">\n\t\t\t\t\t\n\t\t<div id=\"premium-carousel-wrapper-2c6d5d8\" class=\"premium-carousel-wrapper premium-carousel-hidden carousel-wrapper-2c6d5d8  premium-carousel-dots-below\" data-settings=\"{&quot;vertical&quot;:false,&quot;appearance&quot;:&quot;all&quot;,&quot;slidesToShow&quot;:1,&quot;infinite&quot;:true,&quot;speed&quot;:300,&quot;fade&quot;:false,&quot;autoplay&quot;:true,&quot;autoplaySpeed&quot;:5000,&quot;draggable&quot;:true,&quot;touchMove&quot;:true,&quot;adaptiveHeight&quot;:false,&quot;variableWidth&quot;:false,&quot;cssEase&quot;:&quot;ease&quot;,&quot;pauseOnHover&quot;:false,&quot;centerMode&quot;:false,&quot;arrows&quot;:true,&quot;dots&quot;:true,&quot;slidesDesk&quot;:1,&quot;slidesTab&quot;:1,&quot;slidesMob&quot;:1,&quot;animation&quot;:&quot;null&quot;,&quot;tabletBreak&quot;:1025,&quot;mobileBreak&quot;:768,&quot;navigation&quot;:[&quot;&quot;,&quot;&quot;,&quot;&quot;],&quot;carouselNavigation&quot;:&quot;dots&quot;,&quot;templatesNumber&quot;:3}\">\n\t\t\t\t\t\t\t\t<div class=\"premium-carousel-nav-dot\">\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-circle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-carousel-nav-arrow-prev\">\n\t\t\t\t\t<a type=\"button\" data-role=\"none\" class=\"carousel-arrow carousel-prev\" aria-label=\"Previous\" role=\"button\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-angle-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"premium-carousel-nav-arrow-next\">\n\t\t\t\t\t\t<a type=\"button\" data-role=\"none\" class=\"carousel-arrow carousel-next\" aria-label=\"Next\" role=\"button\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-angle-right\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div id=\"premium-carousel-2c6d5d8\" class=\"premium-carousel-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-carousel-template item-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59e72f0 e-con-full e-flex e-con e-child\" data-id=\"59e72f0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64ed8c0 elementor-widget elementor-widget-spacer\" data-id=\"64ed8c0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c224c1f elementor-widget elementor-widget-heading\" data-id=\"c224c1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Teilnehmendenstimmen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6682198 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"6682198\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/12\/testimonial_training_001_en.jpg\" alt=\"testimonial_training_001_en\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/12\/testimonial_training_002_en.jpg\" alt=\"testimonial_training_002_en\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/12\/testimonial_training_003_en.jpg\" alt=\"testimonial_training_003_en\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/ilonalipp.de\/wp-content\/uploads\/2025\/12\/testimonial_training_004_en.jpg\" alt=\"testimonial_training_004_en\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Do you want to improve specific skills? Do you want to facilitate efficient research at your institution? Customised training can help! I provide trainings tailored to your needs. My trainings focus on skills that are crucial for scientists in academia (learn more about my&nbsp;academic background and CV).&nbsp; Possible training formats include&nbsp; In person trainings and [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-68","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/ilonalipp.de\/de\/wp-json\/wp\/v2\/pages\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ilonalipp.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ilonalipp.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ilonalipp.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ilonalipp.de\/de\/wp-json\/wp\/v2\/comments?post=68"}],"version-history":[{"count":10,"href":"https:\/\/ilonalipp.de\/de\/wp-json\/wp\/v2\/pages\/68\/revisions"}],"predecessor-version":[{"id":488,"href":"https:\/\/ilonalipp.de\/de\/wp-json\/wp\/v2\/pages\/68\/revisions\/488"}],"wp:attachment":[{"href":"https:\/\/ilonalipp.de\/de\/wp-json\/wp\/v2\/media?parent=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}